{"id":817,"count":1,"description":"","link":"https:\/\/www.notebook-doktor.de\/en\/tag\/kurzschloss","name":"Kurzschloss","slug":"kurzschloss","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kurzschloss Archive &#8226; Notebook-Doktor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notebook-doktor.de\/en\/tag\/kurzschloss\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kurzschloss Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notebook-doktor.de\/en\/tag\/kurzschloss\" \/>\n<meta property=\"og:site_name\" content=\"Notebook-Doktor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@notebook_dr\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en\\\/tag\\\/kurzschloss\",\"url\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en\\\/tag\\\/kurzschloss\",\"name\":\"Kurzschloss Archive &#8226; Notebook-Doktor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en\\\/tag\\\/kurzschloss#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en\\\/tag\\\/kurzschloss#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kurzschloss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en#website\",\"url\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en\",\"name\":\"Notebook-Doktor\",\"description\":\"Zuverl\u00e4ssige und schnelle Notebook Reparatur Werkstatt\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en#organization\",\"name\":\"Notebook-Doktor.de\",\"url\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notebook-doktor.de\\\/wp-content\\\/uploads\\\/notebook_doktor.png\",\"contentUrl\":\"https:\\\/\\\/www.notebook-doktor.de\\\/wp-content\\\/uploads\\\/notebook_doktor.png\",\"width\":500,\"height\":500,\"caption\":\"Notebook-Doktor.de\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notebook-doktor.de\\\/en#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notebook.doktor\",\"https:\\\/\\\/x.com\\\/notebook_dr\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NotebookDoktor\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kurzschloss Archive &#8226; Notebook-Doktor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notebook-doktor.de\/en\/tag\/kurzschloss","og_locale":"en_US","og_type":"article","og_title":"Kurzschloss Archive","og_url":"https:\/\/www.notebook-doktor.de\/en\/tag\/kurzschloss","og_site_name":"Notebook-Doktor","twitter_card":"summary_large_image","twitter_site":"@notebook_dr","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.notebook-doktor.de\/en\/tag\/kurzschloss","url":"https:\/\/www.notebook-doktor.de\/en\/tag\/kurzschloss","name":"Kurzschloss Archive &#8226; Notebook-Doktor","isPartOf":{"@id":"https:\/\/www.notebook-doktor.de\/en#website"},"breadcrumb":{"@id":"https:\/\/www.notebook-doktor.de\/en\/tag\/kurzschloss#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.notebook-doktor.de\/en\/tag\/kurzschloss#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.notebook-doktor.de\/en"},{"@type":"ListItem","position":2,"name":"Kurzschloss"}]},{"@type":"WebSite","@id":"https:\/\/www.notebook-doktor.de\/en#website","url":"https:\/\/www.notebook-doktor.de\/en","name":"Notebook-Doktor","description":"Zuverl\u00e4ssige und schnelle Notebook Reparatur Werkstatt","publisher":{"@id":"https:\/\/www.notebook-doktor.de\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notebook-doktor.de\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.notebook-doktor.de\/en#organization","name":"Notebook-Doktor.de","url":"https:\/\/www.notebook-doktor.de\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.notebook-doktor.de\/en#\/schema\/logo\/image\/","url":"https:\/\/www.notebook-doktor.de\/wp-content\/uploads\/notebook_doktor.png","contentUrl":"https:\/\/www.notebook-doktor.de\/wp-content\/uploads\/notebook_doktor.png","width":500,"height":500,"caption":"Notebook-Doktor.de"},"image":{"@id":"https:\/\/www.notebook-doktor.de\/en#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notebook.doktor","https:\/\/x.com\/notebook_dr","https:\/\/www.youtube.com\/user\/NotebookDoktor"]}]}},"_links":{"self":[{"href":"https:\/\/www.notebook-doktor.de\/en\/wp-json\/wp\/v2\/tags\/817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notebook-doktor.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.notebook-doktor.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.notebook-doktor.de\/en\/wp-json\/wp\/v2\/posts?tags=817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}